{"id":1912,"date":"2024-09-27T17:53:24","date_gmt":"2024-09-27T17:53:24","guid":{"rendered":"https:\/\/emvets.wpenginepowered.com\/rome\/?p=1912"},"modified":"2024-09-27T17:53:24","modified_gmt":"2024-09-27T17:53:24","slug":"midnight-oreo","status":"publish","type":"post","link":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/","title":{"rendered":"Midnight &amp; Oreo"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":1913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pet-of-the-month"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Midnight &amp; Oreo - Rome<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Midnight &amp; Oreo - Rome\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/\" \/>\n<meta property=\"og:site_name\" content=\"Rome\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-27T17:53:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emvets.com\/rome\/wp-content\/uploads\/sites\/3\/2024\/09\/Midnight-Oreo-Rome-Oct-web-page-2024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"518\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"connierice\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"connierice\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/\"},\"author\":{\"name\":\"connierice\",\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/#\\\/schema\\\/person\\\/d636d85a64236f44e85bee9802c3407e\"},\"headline\":\"Midnight &amp; Oreo\",\"datePublished\":\"2024-09-27T17:53:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/\"},\"wordCount\":3,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emvets.com\\\/rome\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Midnight-Oreo-Rome-Oct-web-page-2024.png\",\"articleSection\":[\"Pet of the Month\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/\",\"url\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/\",\"name\":\"Midnight &amp; Oreo - Rome\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/emvets.com\\\/rome\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Midnight-Oreo-Rome-Oct-web-page-2024.png\",\"datePublished\":\"2024-09-27T17:53:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/#\\\/schema\\\/person\\\/d636d85a64236f44e85bee9802c3407e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/emvets.com\\\/rome\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Midnight-Oreo-Rome-Oct-web-page-2024.png\",\"contentUrl\":\"https:\\\/\\\/emvets.com\\\/rome\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/09\\\/Midnight-Oreo-Rome-Oct-web-page-2024.png\",\"width\":518,\"height\":537},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/2024\\\/09\\\/27\\\/midnight-oreo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/emvets.com\\\/rome\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Midnight &amp; Oreo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/#website\",\"url\":\"https:\\\/\\\/emvets.com\\\/rome\\\/\",\"name\":\"Rome\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/emvets.com\\\/rome\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/emvets.com\\\/rome\\\/#\\\/schema\\\/person\\\/d636d85a64236f44e85bee9802c3407e\",\"name\":\"connierice\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cae0d144c7bd9508219ad5a19fb319ac97b09fa7554dc8fec663bbaaf9555c5e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cae0d144c7bd9508219ad5a19fb319ac97b09fa7554dc8fec663bbaaf9555c5e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cae0d144c7bd9508219ad5a19fb319ac97b09fa7554dc8fec663bbaaf9555c5e?s=96&d=mm&r=g\",\"caption\":\"connierice\"},\"url\":\"https:\\\/\\\/emvets.com\\\/rome\\\/author\\\/connierice\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Midnight &amp; Oreo - Rome","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/","og_locale":"en_US","og_type":"article","og_title":"Midnight &amp; Oreo - Rome","og_url":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/","og_site_name":"Rome","article_published_time":"2024-09-27T17:53:24+00:00","og_image":[{"width":518,"height":537,"url":"https:\/\/emvets.com\/rome\/wp-content\/uploads\/sites\/3\/2024\/09\/Midnight-Oreo-Rome-Oct-web-page-2024.png","type":"image\/png"}],"author":"connierice","twitter_card":"summary_large_image","twitter_misc":{"Written by":"connierice","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#article","isPartOf":{"@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/"},"author":{"name":"connierice","@id":"https:\/\/emvets.com\/rome\/#\/schema\/person\/d636d85a64236f44e85bee9802c3407e"},"headline":"Midnight &amp; Oreo","datePublished":"2024-09-27T17:53:24+00:00","mainEntityOfPage":{"@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/"},"wordCount":3,"commentCount":0,"image":{"@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#primaryimage"},"thumbnailUrl":"https:\/\/emvets.com\/rome\/wp-content\/uploads\/sites\/3\/2024\/09\/Midnight-Oreo-Rome-Oct-web-page-2024.png","articleSection":["Pet of the Month"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/","url":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/","name":"Midnight &amp; Oreo - Rome","isPartOf":{"@id":"https:\/\/emvets.com\/rome\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#primaryimage"},"image":{"@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#primaryimage"},"thumbnailUrl":"https:\/\/emvets.com\/rome\/wp-content\/uploads\/sites\/3\/2024\/09\/Midnight-Oreo-Rome-Oct-web-page-2024.png","datePublished":"2024-09-27T17:53:24+00:00","author":{"@id":"https:\/\/emvets.com\/rome\/#\/schema\/person\/d636d85a64236f44e85bee9802c3407e"},"breadcrumb":{"@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#primaryimage","url":"https:\/\/emvets.com\/rome\/wp-content\/uploads\/sites\/3\/2024\/09\/Midnight-Oreo-Rome-Oct-web-page-2024.png","contentUrl":"https:\/\/emvets.com\/rome\/wp-content\/uploads\/sites\/3\/2024\/09\/Midnight-Oreo-Rome-Oct-web-page-2024.png","width":518,"height":537},{"@type":"BreadcrumbList","@id":"https:\/\/emvets.com\/rome\/2024\/09\/27\/midnight-oreo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/emvets.com\/rome\/"},{"@type":"ListItem","position":2,"name":"Midnight &amp; Oreo"}]},{"@type":"WebSite","@id":"https:\/\/emvets.com\/rome\/#website","url":"https:\/\/emvets.com\/rome\/","name":"Rome","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emvets.com\/rome\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/emvets.com\/rome\/#\/schema\/person\/d636d85a64236f44e85bee9802c3407e","name":"connierice","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/cae0d144c7bd9508219ad5a19fb319ac97b09fa7554dc8fec663bbaaf9555c5e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cae0d144c7bd9508219ad5a19fb319ac97b09fa7554dc8fec663bbaaf9555c5e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cae0d144c7bd9508219ad5a19fb319ac97b09fa7554dc8fec663bbaaf9555c5e?s=96&d=mm&r=g","caption":"connierice"},"url":"https:\/\/emvets.com\/rome\/author\/connierice\/"}]}},"_links":{"self":[{"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/posts\/1912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/comments?post=1912"}],"version-history":[{"count":0,"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/posts\/1912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/media?parent=1912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/categories?post=1912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/emvets.com\/rome\/wp-json\/wp\/v2\/tags?post=1912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}